{"id":595,"date":"2021-05-11T21:23:40","date_gmt":"2021-05-11T19:23:40","guid":{"rendered":"http:\/\/www.avotreservice-sap.com\/?page_id=595"},"modified":"2021-05-17T13:43:24","modified_gmt":"2021-05-17T11:43:24","slug":"nos-clients-parlent-de-nou","status":"publish","type":"page","link":"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/","title":{"rendered":"Nos clients parlent de nous"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"595\" class=\"elementor elementor-595\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38e97985 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"38e97985\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bff12f1\" data-id=\"3bff12f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89dd431 elementor-widget elementor-widget-text-editor\" data-id=\"89dd431\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h1>Ce que les gens pensent de nous<\/h1>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6a2b3 elementor-widget elementor-widget-text-editor\" data-id=\"c6a2b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5>Camille,<\/h5>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f20cea elementor-widget elementor-widget-text-editor\" data-id=\"6f20cea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Apr\u00e8s mon temps partiel, j\u2019ai d\u00fb faire appel \u00e0 une nounou les mercredis apr\u00e8s-midis. J\u2019ai fait appel \u00e0<br \/>A votre service qui a cibl\u00e9 au mieux ma demande. Nous avons notre nounou et nous en sommes<br \/>ravis. Les enfants l\u2019adorent et nous aussi\u00a0\u00bb<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cfe7cf elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"3cfe7cf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0cf746\" data-id=\"d0cf746\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35e2921 elementor-widget elementor-widget-text-editor\" data-id=\"35e2921\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5>Cl\u00e9mentine,<\/h5>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8a1109 elementor-widget elementor-widget-text-editor\" data-id=\"f8a1109\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00ab\u00a0Avec mon mari, nous en avons eu assez de apsser nos week end \u00e0 faire du m\u00e9nage. Nous avons<br \/>donc fait appel \u00e0 A votre service. Disponibilit\u00e9, rendez-vous physique pour \u00e9valuer nos besoins.<br \/>Emilie nous a fait une proposition qui correspond \u00e0 tout point \u00e0 notre besoin. Quel plaisir de rentrer<br \/>chez moi et de trouver une maison toute propre\u00a0\u00bb<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3746a36 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"3746a36\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c461d\" data-id=\"42c461d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb8cbc3 elementor-widget elementor-widget-text-editor\" data-id=\"bb8cbc3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5>Damien,<\/h5>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f37bf0 elementor-widget elementor-widget-text-editor\" data-id=\"9f37bf0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00ab\u00a0Papa solo une semaine sur deux, je commence le travail tr\u00e8s t\u00f4t. A votre service m\u2019a trouv\u00e9 la<br \/>nounou parfaite qui r\u00e9veillent mes enfants en douceur et les d\u00e9posent \u00e0 l\u2019\u00e9cole. Merci\u00a0\u00bb<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4a16d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"f4a16d2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae314b8\" data-id=\"ae314b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-443a077 elementor-widget elementor-widget-text-editor\" data-id=\"443a077\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5>Suzanne,<\/h5>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-183f503 elementor-widget elementor-widget-text-editor\" data-id=\"183f503\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00ab\u00a0En tombant, je me suis cass\u00e9e le F\u00e9mur. J\u2019ai trouv\u00e9 la publicit\u00e9 d\u2019A votre service dans ma bo\u00eete aux<br \/>lettres et j\u2019ai appel\u00e9. Pour une fois, j\u2019ai pu me trouver sans mes enfants et sans internet. Emilie et<br \/>Aur\u00e9lie sont vraiment gentilles et j\u2019ai pu rester chez moi avec Alison qui me livre les courses et me<br \/>fait le m\u00e9nage.\u00a0\u00bb<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ce que les gens pensent de nous Camille, Apr\u00e8s mon temps partiel, j\u2019ai d\u00fb faire appel \u00e0 une nounou les mercredis apr\u00e8s-midis. J\u2019ai fait appel \u00e0 A votre service qui a cibl\u00e9 au mieux ma demande. Nous avons notre nounou et nous en sommes ravis&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"spay_email":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nos clients parlent de nous - A Votre Service - Service d&#039;aide \u00e0 la personn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos clients parlent de nous - A Votre Service - Service d&#039;aide \u00e0 la personn\" \/>\n<meta property=\"og:description\" content=\"Ce que les gens pensent de nous Camille, Apr\u00e8s mon temps partiel, j\u2019ai d\u00fb faire appel \u00e0 une nounou les mercredis apr\u00e8s-midis. J\u2019ai fait appel \u00e0 A votre service qui a cibl\u00e9 au mieux ma demande. Nous avons notre nounou et nous en sommes ravis....\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/\" \/>\n<meta property=\"og:site_name\" content=\"A Votre Service - Service d&#039;aide \u00e0 la personn\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-17T11:43:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/\",\"url\":\"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/\",\"name\":\"Nos clients parlent de nous - A Votre Service - Service d&#039;aide \u00e0 la personn\",\"isPartOf\":{\"@id\":\"http:\/\/www.avotreservice-sap.com\/#website\"},\"datePublished\":\"2021-05-11T19:23:40+00:00\",\"dateModified\":\"2021-05-17T11:43:24+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/www.avotreservice-sap.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos clients parlent de nous\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.avotreservice-sap.com\/#website\",\"url\":\"http:\/\/www.avotreservice-sap.com\/\",\"name\":\"A Votre Service - Service d&#039;aide \u00e0 la personn\",\"description\":\"Osez vous lib\u00e9rez l\u2019esprit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.avotreservice-sap.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos clients parlent de nous - A Votre Service - Service d&#039;aide \u00e0 la personn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/","og_locale":"en_US","og_type":"article","og_title":"Nos clients parlent de nous - A Votre Service - Service d&#039;aide \u00e0 la personn","og_description":"Ce que les gens pensent de nous Camille, Apr\u00e8s mon temps partiel, j\u2019ai d\u00fb faire appel \u00e0 une nounou les mercredis apr\u00e8s-midis. J\u2019ai fait appel \u00e0 A votre service qui a cibl\u00e9 au mieux ma demande. Nous avons notre nounou et nous en sommes ravis....","og_url":"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/","og_site_name":"A Votre Service - Service d&#039;aide \u00e0 la personn","article_modified_time":"2021-05-17T11:43:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/","url":"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/","name":"Nos clients parlent de nous - A Votre Service - Service d&#039;aide \u00e0 la personn","isPartOf":{"@id":"http:\/\/www.avotreservice-sap.com\/#website"},"datePublished":"2021-05-11T19:23:40+00:00","dateModified":"2021-05-17T11:43:24+00:00","breadcrumb":{"@id":"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.avotreservice-sap.com\/index.php\/nos-clients-parlent-de-nou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.avotreservice-sap.com\/"},{"@type":"ListItem","position":2,"name":"Nos clients parlent de nous"}]},{"@type":"WebSite","@id":"http:\/\/www.avotreservice-sap.com\/#website","url":"http:\/\/www.avotreservice-sap.com\/","name":"A Votre Service - Service d&#039;aide \u00e0 la personn","description":"Osez vous lib\u00e9rez l\u2019esprit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.avotreservice-sap.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/pages\/595"}],"collection":[{"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/comments?post=595"}],"version-history":[{"count":6,"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/pages\/595\/revisions"}],"predecessor-version":[{"id":709,"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/pages\/595\/revisions\/709"}],"wp:attachment":[{"href":"http:\/\/www.avotreservice-sap.com\/index.php\/wp-json\/wp\/v2\/media?parent=595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}